{"id":166188,"date":"2024-10-31T13:57:33","date_gmt":"2024-10-31T12:57:33","guid":{"rendered":"https:\/\/ecsa-chemicals.ch\/prodotto\/mp-037794-2\/"},"modified":"2024-10-31T13:57:33","modified_gmt":"2024-10-31T12:57:33","slug":"mp-037794-2","status":"publish","type":"product","link":"https:\/\/ecsa-chemicals.ch\/fr\/produit\/mp-037794-2\/","title":{"rendered":"MP 037794"},"featured_media":0,"template":"","business_unit":[258],"class_list":["post-166188","product","type-product","status-publish","hentry","business_unit-cosmetics-detergents"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.3.1 (Yoast SEO v25.3.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>DEPIL RETARD A\/HGL\/CA11 - MP 037794 Vente en gros | ECSA Chemicals<\/title>\n<meta name=\"description\" content=\"ECSA Chemicals fournisseur et distributeur de DEPIL RETARD A\/HGL\/CA11 (MP 037794) pour l\u2019industrie. Vente en gros en Suisse et UE. Demandez une offre\u202f!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ecsa-chemicals.ch\/fr\/produit\/mp-037794-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MP 037794\" \/>\n<meta property=\"og:description\" content=\"ECSA Chemicals fournisseur et distributeur de DEPIL RETARD A\/HGL\/CA11 (MP 037794) pour l\u2019industrie. Vente en gros en Suisse et UE. Demandez une offre\u202f!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecsa-chemicals.ch\/fr\/produit\/mp-037794-2\/\" \/>\n<meta property=\"og:site_name\" content=\"ECSA Chemicals\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ecsa-chemicals.ch\/fr\/produit\/mp-037794-2\/\",\"url\":\"https:\/\/ecsa-chemicals.ch\/fr\/produit\/mp-037794-2\/\",\"name\":\"DEPIL RETARD A\/HGL\/CA11 - MP 037794 Vente en gros | ECSA Chemicals\",\"isPartOf\":{\"@id\":\"https:\/\/ecsa-chemicals.ch\/fr\/#website\"},\"datePublished\":\"2024-10-31T12:57:33+00:00\",\"description\":\"ECSA Chemicals fournisseur et distributeur de DEPIL RETARD A\/HGL\/CA11 (MP 037794) pour l\u2019industrie. Vente en gros en Suisse et UE. Demandez une offre\u202f!\",\"breadcrumb\":{\"@id\":\"https:\/\/ecsa-chemicals.ch\/fr\/produit\/mp-037794-2\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ecsa-chemicals.ch\/fr\/produit\/mp-037794-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ecsa-chemicals.ch\/fr\/produit\/mp-037794-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ecsa-chemicals.ch\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\/\/ecsa-chemicals.ch\/fr\/produit\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MP 037794\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ecsa-chemicals.ch\/fr\/#website\",\"url\":\"https:\/\/ecsa-chemicals.ch\/fr\/\",\"name\":\"ECSA Chemicals\",\"description\":\"ECSA Chemicals\",\"publisher\":{\"@id\":\"https:\/\/ecsa-chemicals.ch\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ecsa-chemicals.ch\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ecsa-chemicals.ch\/fr\/#organization\",\"name\":\"ECSA Chemicals\",\"url\":\"https:\/\/ecsa-chemicals.ch\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/ecsa-chemicals.ch\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/esycif8nzka.exactdn.com\/wp-content\/uploads\/2025\/02\/ecsa-chemicals-logo.jpg?strip=all&lossy=1&ssl=1\",\"contentUrl\":\"https:\/\/esycif8nzka.exactdn.com\/wp-content\/uploads\/2025\/02\/ecsa-chemicals-logo.jpg?strip=all&lossy=1&ssl=1\",\"width\":800,\"height\":800,\"caption\":\"ECSA Chemicals\"},\"image\":{\"@id\":\"https:\/\/ecsa-chemicals.ch\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"DEPIL RETARD A\/HGL\/CA11 - MP 037794 Vente en gros | ECSA Chemicals","description":"ECSA Chemicals fournisseur et distributeur de DEPIL RETARD A\/HGL\/CA11 (MP 037794) pour l\u2019industrie. Vente en gros en Suisse et UE. Demandez une offre\u202f!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ecsa-chemicals.ch\/fr\/produit\/mp-037794-2\/","og_locale":"fr_FR","og_type":"article","og_title":"MP 037794","og_description":"ECSA Chemicals fournisseur et distributeur de DEPIL RETARD A\/HGL\/CA11 (MP 037794) pour l\u2019industrie. Vente en gros en Suisse et UE. Demandez une offre\u202f!","og_url":"https:\/\/ecsa-chemicals.ch\/fr\/produit\/mp-037794-2\/","og_site_name":"ECSA Chemicals","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ecsa-chemicals.ch\/fr\/produit\/mp-037794-2\/","url":"https:\/\/ecsa-chemicals.ch\/fr\/produit\/mp-037794-2\/","name":"DEPIL RETARD A\/HGL\/CA11 - MP 037794 Vente en gros | ECSA Chemicals","isPartOf":{"@id":"https:\/\/ecsa-chemicals.ch\/fr\/#website"},"datePublished":"2024-10-31T12:57:33+00:00","description":"ECSA Chemicals fournisseur et distributeur de DEPIL RETARD A\/HGL\/CA11 (MP 037794) pour l\u2019industrie. Vente en gros en Suisse et UE. Demandez une offre\u202f!","breadcrumb":{"@id":"https:\/\/ecsa-chemicals.ch\/fr\/produit\/mp-037794-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecsa-chemicals.ch\/fr\/produit\/mp-037794-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ecsa-chemicals.ch\/fr\/produit\/mp-037794-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ecsa-chemicals.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/ecsa-chemicals.ch\/fr\/produit\/"},{"@type":"ListItem","position":3,"name":"MP 037794"}]},{"@type":"WebSite","@id":"https:\/\/ecsa-chemicals.ch\/fr\/#website","url":"https:\/\/ecsa-chemicals.ch\/fr\/","name":"ECSA Chemicals","description":"ECSA Chemicals","publisher":{"@id":"https:\/\/ecsa-chemicals.ch\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecsa-chemicals.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ecsa-chemicals.ch\/fr\/#organization","name":"ECSA Chemicals","url":"https:\/\/ecsa-chemicals.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ecsa-chemicals.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/esycif8nzka.exactdn.com\/wp-content\/uploads\/2025\/02\/ecsa-chemicals-logo.jpg?strip=all&lossy=1&ssl=1","contentUrl":"https:\/\/esycif8nzka.exactdn.com\/wp-content\/uploads\/2025\/02\/ecsa-chemicals-logo.jpg?strip=all&lossy=1&ssl=1","width":800,"height":800,"caption":"ECSA Chemicals"},"image":{"@id":"https:\/\/ecsa-chemicals.ch\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ecsa-chemicals.ch\/fr\/wp-json\/wp\/v2\/product\/166188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecsa-chemicals.ch\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ecsa-chemicals.ch\/fr\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/ecsa-chemicals.ch\/fr\/wp-json\/wp\/v2\/product\/166188\/revisions"}],"wp:attachment":[{"href":"https:\/\/ecsa-chemicals.ch\/fr\/wp-json\/wp\/v2\/media?parent=166188"}],"wp:term":[{"taxonomy":"business_unit","embeddable":true,"href":"https:\/\/ecsa-chemicals.ch\/fr\/wp-json\/wp\/v2\/business_unit?post=166188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}